{"id":7245,"date":"2022-09-20T18:02:51","date_gmt":"2022-09-20T21:02:51","guid":{"rendered":"https:\/\/temp.leadster.com.br\/blog\/?p=7245"},"modified":"2023-03-09T11:16:11","modified_gmt":"2023-03-09T14:16:11","slug":"utm","status":"publish","type":"post","link":"https:\/\/leadster.com.br\/blog\/utm\/","title":{"rendered":"UTM: Aprenda O Que \u00c9, Como Funciona e Seus Par\u00e2metros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vamos falar sobre mais uma das dezenas de siglas que existem no marketing digital. Dessa vez, exploraremos os par\u00e2metros UTM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em resumo, sem dar muitos spoilers, \u00e9 por meio dos par\u00e2metros UTM que \u00e9 poss\u00edvel rastrear o tr\u00e1fego do seu site.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bom, s\u00f3 com essa informa\u00e7\u00e3o j\u00e1 conseguimos perceber a import\u00e2ncia desse t\u00f3pico. Mesmo assim, o UTM ainda n\u00e3o \u00e9 t\u00e3o comumente utilizado por profissionais de marketing devido ao seu n\u00edvel de dificuldade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, fique tranquilo, vou tratar esse assunto da maneira mais objetiva e completa poss\u00edvel.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siga no texto para tirar todas as suas d\u00favidas!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 UTM?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/O-que-e-UTM.webp\" alt=\"O que \u00e9 UTM?\" class=\"wp-image-7253\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/O-que-e-UTM.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/O-que-e-UTM-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/O-que-e-UTM-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O<em> Urchin Traffic Monitor<\/em>, Monitor de Tr\u00e1fego de Urchin, ou apenas UTM, \u00e9 um <strong>conjunto de par\u00e2metros, respons\u00e1veis por rastrear as visitas de uma p\u00e1gina<\/strong> em espec\u00edfico, por meio de c\u00f3digos adicionados ao final de uma URL.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou seja, com os par\u00e2metros UTM voc\u00ea conseguir\u00e1 analisar de onde o visitante veio, auxiliando na compreens\u00e3o da empresa sobre o <strong>comportamento do usu\u00e1rio<\/strong>, al\u00e9m de avaliar quais s\u00e3o os canais que est\u00e3o dando mais resultado ao seu site.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o UTM Funciona?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Como-UTM-Funciona.webp\" alt=\"Como o UTM funciona\" class=\"wp-image-7249\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Como-UTM-Funciona.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Como-UTM-Funciona-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Como-UTM-Funciona-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para o UTM funcionar, voc\u00ea precisa ter em m\u00e3os a<strong> URL da p\u00e1gina de destino dos usu\u00e1rios<\/strong>. Em seguida, voc\u00ea precisar\u00e1 <strong>adicionar \u201c?\u201d e os par\u00e2metros UTM<\/strong> na URL, que explicaremos em breve &#8211; esse \u00e9 o c\u00f3digo do qual falamos no t\u00f3pico anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o link completo, chegou a hora de decidir onde coloc\u00e1-lo, ou seja, em redes sociais, e-mail, blog, an\u00fancios etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pronto, com o seu link pronto e bem colocado, voc\u00ea conseguir\u00e1 analisar o tr\u00e1fego de seu site por meio do <a href=\"https:\/\/leadster.com.br\/blog\/google-analytics-para-gerar-conversoes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Analytics<\/a>!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Voc\u00ea Conhece a Import\u00e2ncia de Usar UTMs no Marketing Digital?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Voce-Sabe-a-Importancia-de-Usar-UTMs-no-Marketing-Digital.webp\" alt=\"Import\u00e2ncia das UTMs no marketing digital\" class=\"wp-image-7256\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Voce-Sabe-a-Importancia-de-Usar-UTMs-no-Marketing-Digital.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Voce-Sabe-a-Importancia-de-Usar-UTMs-no-Marketing-Digital-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Voce-Sabe-a-Importancia-de-Usar-UTMs-no-Marketing-Digital-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ao analisar as UTMs e descobrir de onde os seus usu\u00e1rios vieram, voc\u00ea consegue tomar decis\u00f5es mais assertivas quanto \u00e0s suas estrat\u00e9gias de marketing. Al\u00e9m de nichar ainda mais os canais que trazem resultado ao seu neg\u00f3cio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos agora entender mais sobre as vantagens e desvantagens de usar UTMs no Marketing Digital.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Rastreamento das fontes de tr\u00e1fego<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quer saber<strong> qual canal est\u00e1 trazendo mais tr\u00e1fego para o seu site<\/strong>? Pois bem, o UTM permite voc\u00ea analisar isso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir desse ponto, voc\u00ea poder\u00e1 pensar nas estrat\u00e9gias direcionadas para essa m\u00eddia.<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/canais-de-geracao-de-leads-para-pequenas-empresas\/\"><em>5 Melhores Canais de Gera\u00e7\u00e3o de Leads para Pequenas Empresas<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">2. Acompanhe suas campanhas<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea est\u00e1 pensando em descobrir <strong>quanto resultado a sua nova campanha vai trazer ao seu site<\/strong>, o UTM tamb\u00e9m est\u00e1 a\u00ed para isso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea s\u00f3 precisar\u00e1 adicionar o nome da campanha na UTM de todos os links e an\u00fancios dessa promo\u00e7\u00e3o.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/leadster.com.br\/materiais\/plano-de-midia-paga\/?utm_source=banner_blog&amp;utm_medium=organic&amp;utm_campaign=post_tofu&amp;utm_content=utm\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"382\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-1024x382.webp\" alt=\"\" class=\"wp-image-10500\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-1024x382.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-300x112.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-768x287.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-150x56.webp 150w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia.webp 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/dashboard\/\"><em>O que \u00e9 Dashboard e Como Criar um Painel para Demonstrar os Resultados da sua Equipe<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">3. Otimiza\u00e7\u00e3o dos an\u00fancios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para melhorar o desempenho de seus an\u00fancios, voc\u00ea pode usar os <strong>testes A\/B junto aos UTMs<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Basta adicionar um par\u00e2metro diferente para cada uma das imagens testadas e, ao final, descobrir qual formato teve o melhor resultado.<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/teste-a-b\/\"><em>Descubra a Import\u00e2ncia do Teste A\/B para Aumentar Resultados<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">4. Voc\u00ea passa a conhecer seu cliente<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ao analisar de onde o seu visitante vem, voc\u00ea consegue entender mais sobre seus h\u00e1bitos de pesquisa e interesse. Ou seja, sua empresa tem a chance de conhec\u00ea-lo melhor e proporcionar uma experi\u00eancia mais personalizada.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5. Economia de investimento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quando voc\u00ea descobre o que est\u00e1 dando certo para o seu neg\u00f3cio, seja em estrat\u00e9gias, an\u00fancios, conte\u00fados ou tipos de canais, voc\u00ea d\u00e1 <strong>maior foco ao que est\u00e1 dando mais resultado<\/strong>. Dessa forma, seu investimento nas demais alternativas diminui, uma vez que n\u00e3o est\u00e3o trazendo tanto retorno.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Maior lucratividade para os seus neg\u00f3cios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Quanto mais informa\u00e7\u00f5es voc\u00ea tiver sobre o seu cliente, mais personalizada ser\u00e1 a experi\u00eancia proporcionada e, consequentemente, o <strong>p\u00fablico ficar\u00e1 mais satisfeito<\/strong>, aumentando suas chances de venda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m dessa quest\u00e3o, com a diminui\u00e7\u00e3o dos investimentos em estrat\u00e9gias que n\u00e3o trazem retorno, seus resultados tamb\u00e9m tendem a melhorar.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os Par\u00e2metros de UTM?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Quais-sao-os-Parametros-de-UTM.webp\" alt=\"Quais s\u00e3o os Par\u00e2metros de UTM?\" class=\"wp-image-7254\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Quais-sao-os-Parametros-de-UTM.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Quais-sao-os-Parametros-de-UTM-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Quais-sao-os-Parametros-de-UTM-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Os par\u00e2metros de UTM s\u00e3o as vari\u00e1veis utilizadas para rastrear o tr\u00e1fego do seu site. Por isso, \u00e9 importante entender cada um deles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos l\u00e1!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Campaign<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este par\u00e2metro \u00e9 utilizado para <strong>identificar o nome da campanha de marketing<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O UTM campaign \u00e9 normalmente usado se h\u00e1 uma campanha estrat\u00e9gica, produto espec\u00edfico em promo\u00e7\u00e3o, palavra-chave importante, entre outros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplo: leadster.com.br\/blog\/?utm_source=instagram&amp;utm_medium=post&amp;utm_content=home&amp;<strong>utm_campaign=black_friday<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aten\u00e7\u00e3o: <\/strong>este par\u00e2metro \u00e9 obrigat\u00f3rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Source<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No UTM Source \u00e9 necess\u00e1rio inserir a <strong>origem de tr\u00e1fego<\/strong>. Ou seja, voc\u00ea precisa informar em que local a sua campanha ser\u00e1 exibida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9 poss\u00edvel colocar o nome da rede social, blog, e-mail, pop-up etc.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplo: leadster.com.br\/blog\/?<strong>utm_source=instagram<\/strong>&amp;utm_medium=post&amp;utm_content=home&amp;utm_campaign=black_friday<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aten\u00e7\u00e3o: <\/strong>este par\u00e2metro \u00e9 obrigat\u00f3rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Medium<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">No par\u00e2metro UTM Medium \u00e9 preciso especificar qual o meio ou local onde o link foi compartilhado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea por qual m\u00edda as pessoas ir\u00e3o chegar a sua p\u00e1gina, como CPC, e-mail, banner, redes sociais, display, e-book, entre outros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplo: leadster.com.br\/blog\/?utm_source=instagram&amp;<strong>utm_medium=post<\/strong>&amp;utm_content=home&amp;utm_campaign=black_friday<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Aten\u00e7\u00e3o: <\/strong>este par\u00e2metro \u00e9 obrigat\u00f3rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Content<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O UTM content \u00e9 um par\u00e2metro opcional, usado quando \u00e9 necess\u00e1rio identificar uma <strong>campanha em especial<\/strong> ou quando se est\u00e1 fazendo<strong> testes A\/B<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplo: leadster.com.br\/blog\/?utm_source=instagram&amp;utm_medium=post&amp;<strong>utm_content=testea<\/strong>&amp;utm_campaign=black_friday<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Term<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Este par\u00e2metro opcional serve para <strong>identificar a palavra-chave<\/strong> usada na campanha. O UTM term \u00e9 muito utilizado no Google Ads.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exemplo: leadster.com.br\/blog\/?utm_source=google&amp;utm_medium=cpc&amp;utm_campaign=black_friday&amp;utm_term=<strong>chatbot_para_geracao_de_leads<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onde Usar os Par\u00e2metros UTM?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Onde-Usar-os-Parametros-UTM.webp\" alt=\"Onde Usar os Par\u00e2metros UTM?\" class=\"wp-image-7252\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Onde-Usar-os-Parametros-UTM.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Onde-Usar-os-Parametros-UTM-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Onde-Usar-os-Parametros-UTM-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Agora que voc\u00ea j\u00e1 sabe quais s\u00e3o os par\u00e2metros UTM e sua import\u00e2ncia, vamos aos canais em que essa estrat\u00e9gia pode ser aplicada!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Redes Sociais<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m de descobrir quais redes sociais est\u00e3o trazendo mais tr\u00e1fego, atrav\u00e9s da UTM voc\u00ea tamb\u00e9m poder\u00e1 analisar quais dos links postados est\u00e3o engajando mais a audi\u00eancia.&nbsp;<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/pixel-do-facebook\/\"><em>Pixel do Facebook: Para que Serve e Como Configurar no Site?<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">An\u00fancios<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Os an\u00fancios de m\u00eddias pagas tamb\u00e9m podem ser monitorados por meio do UTMs. A partir dos par\u00e2metros definidos, voc\u00ea poder\u00e1 <strong>medir o desempenho dos seus an\u00fancios<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa an\u00e1lise serve para qualquer formato, desde imagens e banners at\u00e9 links patrocinados.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/leadster.com.br\/leads-qualificados-com-anuncios\/?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=post_utm\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-1024x341.webp\" alt=\"\" class=\"wp-image-6929\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-1024x341.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-300x100.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-768x256.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-1536x512.webp 1536w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-2048x683.webp 2048w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/12-150x50.webp 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Parcerias<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">As parcerias que voc\u00ea faz, como<strong> posts patrocinados<\/strong>, <strong>conte\u00fados com convidados<\/strong> e banners, imagens e links de parceiros tamb\u00e9m podem ter o tr\u00e1fego rastreado pelo UTM.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">E-mail<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Sabe os <strong>links que voc\u00ea coloca em seus e-mails<\/strong>? Ent\u00e3o, eles tamb\u00e9m podem ser rastreados pelos par\u00e2metros UTM.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dessa forma, voc\u00ea pode conferir como andam os cliques nos e-mails enviados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Crie um c\u00f3digo UTM com essas 6 etapas<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas.webp\" alt=\"Crie um c\u00f3digo UTM com essas 6 etapas\" class=\"wp-image-7250\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Para te auxiliar na cria\u00e7\u00e3o do UTM perfeito para o seu neg\u00f3cio, separamos aqui 6 etapas para se atentar:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1. Defina onde usar os c\u00f3digos UTM<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antes de come\u00e7ar a criar seu c\u00f3digo UTM, <strong>defina onde o link ser\u00e1 colocado<\/strong>, pois essa \u00e9 uma vari\u00e1vel essencial para a estrat\u00e9gia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou seja, seu link ser\u00e1 aplicado nas redes sociais, em an\u00fancios, nos e-mails marketing etc.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Saiba como funcionam os par\u00e2metros UTM<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Voc\u00ea entendeu quais s\u00e3o e como funcionam os par\u00e2metros UTM que explicamos aqui? Pois ser\u00e1 a partir deles que sua an\u00e1lise de tr\u00e1fego ser\u00e1 feita.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Familiarize-se com as vari\u00e1veis \u200b\u200bdos c\u00f3digos UTM<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 sabe quais vari\u00e1veis vai utilizar em seu c\u00f3digo UTM? Lembre-se que algumas delas s\u00e3o obrigat\u00f3rias, enquanto outras s\u00e3o vistas como complementos &#8211; mas eu aconselho utilizar todas para proporcionar uma an\u00e1lise mais completa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4. A hora de criar c\u00f3digos UTM<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para esta etapa voc\u00ea tem duas op\u00e7\u00f5es:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Criar o c\u00f3digo UTM manualmente<\/strong>. Escrevendo o c\u00f3digo completo manualmente;<\/li>\n\n\n\n<li><strong>Criar o c\u00f3digo por meio de um gerador de UTM.<\/strong> Neste caso, voc\u00ea precisa apenas preencher todas as vari\u00e1veis que aparecem na ferramenta, as chamados URL Builders. Vamos \u00e0s mais usadas:\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/ga-dev-tools.web.app\/campaign-url-builder\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gerador de UTM &#8211; Google<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/materiais.resultadosdigitais.com.br\/planilha-gerador-de-utm\" target=\"_blank\" rel=\"noreferrer noopener\">Gerador de UTM &#8211; RD Station<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/ga-dev-tools.web.app\/campaign-url-builder\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-print.webp\" alt=\"\" class=\"wp-image-7251\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-print.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-print-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/Crie-codigo-UTM-com-essas-6-etapas-print-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/figure>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/google-analytics-para-gerar-conversoes\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Como Usar o Google Analytics para Gerar mais Convers\u00f5es no seu Site<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">5. Encurtador de URL<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Eu sei, o tamanho dessa URL ficou gigante e nada bonito de se ver. E fique atento, pois al\u00e9m de n\u00e3o ser bonito, n\u00e3o \u00e9 recomendado como uma boa pr\u00e1tica de marketing URLs grandes. Quanto menor e mais simples a URL, melhor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fique tranquilo que h\u00e1 uma solu\u00e7\u00e3o para isso!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Utilize ferramentas como o <a href=\"https:\/\/bitly.com\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>bitly<\/strong><\/a>, que v\u00e3o ajudar a reduzir o comprimento do seu URL.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">6. Me\u00e7a o seu sucesso e use os dados para melhorar<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Lembre-se: <strong>o que n\u00e3o \u00e9 medido n\u00e3o pode ser melhorado<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desse modo, assim que sua UTM estiver funcionando, j\u00e1 comece a analisar seus resultados. Afinal, foi para isso que voc\u00ea investiu nessa estrat\u00e9gia. Saiba como est\u00e1 sendo gerado o tr\u00e1fego do seu site, quais s\u00e3o os pontos de melhora e tamb\u00e9m o que est\u00e1 bom.<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em><em><img decoding=\"async\" width=\"15\" height=\"15\" class=\"wp-image-2691\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2021\/08\/magnifying-glass.png\" alt=\"\"><\/em><\/em> <em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/relatorios-de-marketing\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Relat\u00f3rios de Marketing: Como criar, M\u00e9tricas e Templates<\/em><\/a><\/pre>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">Chegamos ao fim de mais um conte\u00fado estrat\u00e9gico!&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Viu, os par\u00e2metros UTM, na verdade, n\u00e3o s\u00e3o dif\u00edceis, apenas mal compreendidos, por necessitar de um pouco mais de aten\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por isso, n\u00e3o deixe de investir nessa estrat\u00e9gia de marketing digital.&nbsp;Por fim, para melhorar ainda mais o resultado de suas campanhas, que tal conferir o nosso <a href=\"https:\/\/leadster.com.br\/midia-paga\/\" target=\"_blank\" rel=\"noreferrer noopener\">Guia Completo sobre M\u00eddia Paga<\/a>? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aproveite para testar os seus conhecimentos sobre UTM na hora de criar os seus an\u00fancios!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/leadster.com.br\/midia-paga\/\"><img decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-1024x341.webp\" alt=\"\" class=\"wp-image-7691\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-1024x341.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-300x100.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-768x256.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-150x50.webp 150w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga.webp 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<script type=\"application\/ld+json\">\n{\n  \"@context\": \"https:\/\/schema.org\",\n  \"@type\": \"FAQPage\",\n  \"mainEntity\": [{\n    \"@type\": \"Question\",\n    \"name\": \"O que \u00e9 UTM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"O Urchin Traffic Monitor, Monitor de Tr\u00e1fego de Urchin, ou apenas UTM, \u00e9 um conjunto de par\u00e2metros, respons\u00e1veis por rastrear as visitas de uma p\u00e1gina em espec\u00edfico, por meio de c\u00f3digos adicionados ao final de uma URL.\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Como o UTM Funciona?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Para o UTM funcionar, voc\u00ea precisa ter em m\u00e3os a URL da p\u00e1gina de destino dos usu\u00e1rios. Em seguida, voc\u00ea precisar\u00e1 adicionar \u201c?\u201d e os par\u00e2metros UTM na URL, que explicaremos em breve \u2013 esse \u00e9 o c\u00f3digo do qual falamos no t\u00f3pico anterior.\n\nCom o link completo, chegou a hora de decidir onde coloc\u00e1-lo, ou seja, em redes sociais, e-mail, blog, an\u00fancios etc.\n\nPronto, com o seu link pronto e bem colocado, voc\u00ea conseguir\u00e1 analisar o tr\u00e1fego de seu site por meio do Google Analytics!\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Voc\u00ea Conhece a Import\u00e2ncia de Usar UTMs no Marketing Digital?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Vamos agora entender mais sobre as vantagens e desvantagens de usar UTMs no Marketing Digital.\n\n<ul>\n<li>1. Rastreamento das fontes de tr\u00e1fego<\/li>\n<li>2. Acompanhe suas campanhas<\/li>\n<li>3. Otimiza\u00e7\u00e3o dos an\u00fancios<\/li>\n<li>4. Voc\u00ea passa a conhecer seu cliente<\/li>\n<li>5. Economia de investimento<\/li>\n<li>6. Maior lucratividade para os seus neg\u00f3cios<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Quais s\u00e3o os Par\u00e2metros de UTM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Os par\u00e2metros de UTM s\u00e3o as vari\u00e1veis utilizadas para rastrear o tr\u00e1fego do seu site. Por isso, \u00e9 importante entender cada um deles.\n\nVamos l\u00e1!\n\n<ul>\n<li>Campaign<\/li>\n<li>Source<\/li>\n<li>Medium<\/li>\n<li>Content<\/li>\n<li>Term<\/li>\n<\/ul>\"\n    }\n  },{\n    \"@type\": \"Question\",\n    \"name\": \"Onde Usar os Par\u00e2metros UTM?\",\n    \"acceptedAnswer\": {\n      \"@type\": \"Answer\",\n      \"text\": \"Agora que voc\u00ea j\u00e1 sabe quais s\u00e3o os par\u00e2metros UTM e sua import\u00e2ncia, vamos aos canais em que essa estrat\u00e9gia pode ser aplicada!\n\n<ul>\n<li>Redes Sociais<\/li>\n<li>An\u00fancios<\/li>\n<li>Parcerias<\/li>\n<li>E-mail<\/li>\n<\/ul>\"\n    }\n  }]\n}\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Vamos falar sobre mais uma das dezenas de siglas que existem no marketing digital. Dessa vez, exploraremos os par\u00e2metros UTM. Em resumo, sem dar muitos spoilers, \u00e9 por meio dos par\u00e2metros UTM que \u00e9 poss\u00edvel rastrear o tr\u00e1fego do seu site. Bom, s\u00f3 com essa informa\u00e7\u00e3o j\u00e1 conseguimos perceber a [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":7255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[66,68],"tags":[],"class_list":["post-7245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-digital","category-midia-paga"],"_links":{"self":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/7245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/comments?post=7245"}],"version-history":[{"count":2,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/7245\/revisions"}],"predecessor-version":[{"id":15457,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/7245\/revisions\/15457"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/media\/7255"}],"wp:attachment":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/media?parent=7245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/categories?post=7245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/tags?post=7245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}