{"id":9601,"date":"2022-12-09T17:07:34","date_gmt":"2022-12-09T20:07:34","guid":{"rendered":"https:\/\/temp.leadster.com.br\/blog\/?p=9601"},"modified":"2023-03-09T11:43:47","modified_gmt":"2023-03-09T14:43:47","slug":"pinterest-ads","status":"publish","type":"post","link":"https:\/\/leadster.com.br\/blog\/pinterest-ads\/","title":{"rendered":"Pinterest Ads: Entenda o que \u00e9, suas Vantagens e Como Anunciar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ainda existem algumas pessoas que subestimam o poder do Pinterest, como se a plataforma fosse apenas um local para armazenar fotos e ideias.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas, voc\u00ea sabia que <a href=\"https:\/\/business.pinterest.com\/pt-br\/shopping\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>usu\u00e1rios da rede est\u00e3o dispostos a comprar 50%<\/strong><\/a><strong> mais do que aqueles que n\u00e3o est\u00e3o no canal<\/strong>?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pois \u00e9, essa plataforma pode te surpreender.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ent\u00e3o, vamos conhecer o Pinterest Ads, analisar como ele funciona e aprender a anunciar no canal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Siga no texto!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 Pinterest Ads?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/O-que-e-Pinterest-Ads.webp\" alt=\"O que \u00e9 Pinterest Ads?\" class=\"wp-image-9646\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/O-que-e-Pinterest-Ads.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/O-que-e-Pinterest-Ads-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/O-que-e-Pinterest-Ads-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O <a href=\"https:\/\/business.pinterest.com\/pt-br\/advertise\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pinterest Ads<\/a> \u00e9, assim como outras redes, uma <strong>plataforma que permite a cria\u00e7\u00e3o de an\u00fancios pagos para impulsionar as postagens<\/strong> e fortalecer o reconhecimento da marca.<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/social-ads-gerar-leads\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Social Ads: Como Usar as Redes Sociais para Gerar mais Leads<\/em><\/a><\/pre>\n\n\n\n<h2 class=\"wp-block-heading\">Como Funciona o Pinterest Ads?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Como-Funciona-o-Pinterest-Ads.webp\" alt=\"Como Funciona o Pinterest Ads?\" class=\"wp-image-9644\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Como-Funciona-o-Pinterest-Ads.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Como-Funciona-o-Pinterest-Ads-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Como-Funciona-o-Pinterest-Ads-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O funcionamento do Pinterest Ads \u00e9 parecido com o do <a href=\"https:\/\/leadster.com.br\/blog\/como-anunciar-no-facebook-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook Ads<\/a>, este que possibilita a <strong>cria\u00e7\u00e3o de campanhas publicit\u00e1rias para aqueles com perfil para se tornar um cliente<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Essa plataforma possibilita encontrar clientes em potencial, al\u00e9m de <strong>divulgar a empresa <\/strong>para um grande n\u00famero de pessoas.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/leadster.com.br\/materiais\/plano-de-midia-paga\/?utm_source=banner_blog&amp;utm_medium=organic&amp;utm_campaign=post_tofu&amp;utm_content=pinterest_ads\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"382\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-1024x382.webp\" alt=\"\" class=\"wp-image-10500\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-1024x382.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-300x112.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-768x287.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia-150x56.webp 150w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Plano-de-Midia.webp 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/melhores-canais-de-midia-paga\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>18 Melhores Canais de M\u00eddia Paga para sua Estrat\u00e9gia de Marketing Digital<\/em><\/a><\/pre>\n\n\n\n<h2 class=\"wp-block-heading\">Por que Anunciar no Pinterest Ads?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Por-que-Anunciar-no-Pinterest-Ads.webp\" alt=\"Por que Anunciar no Pinterest Ads?\" class=\"wp-image-9652\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Por-que-Anunciar-no-Pinterest-Ads.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Por-que-Anunciar-no-Pinterest-Ads-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Por-que-Anunciar-no-Pinterest-Ads-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Primeiro de tudo, vamos lembrar o que Mariana Sensini, antiga diretora do Pinterest Brasil, relatou sobre o Pinterest em 2020: logo no in\u00edcio do isolamento, a <a href=\"https:\/\/exame.com\/negocios\/mariana-sensini-do-pinterest-brasil-o-crescimento-em-meio-a-quarentena\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>rede social reunia 38 milh\u00f5es de usu\u00e1rios mensais<\/strong><\/a> e o n\u00famero de<strong> pastas criadas cresceu em 62%<\/strong>. Com isso, podemos afirmar que o Pinterest tem grande influ\u00eancia e potencial de crescimento, al\u00e9m de engajar com o p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ou seja, um dos motivos para anunciar no Pinterest Ads \u00e9 a grande quantidade de usu\u00e1rios, al\u00e9m das seguintes vantagens:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Conseguir a<strong> aten\u00e7\u00e3o do usu\u00e1rio<\/strong> na sua busca por ideias;<\/li>\n\n\n\n<li>Aumentar o alcance e <strong>o reconhecimento da marca<\/strong>;<\/li>\n\n\n\n<li>Acesso a um <strong>p\u00fablico mais nichado<\/strong>, que tem interesse em produtos espec\u00edficos;<\/li>\n\n\n\n<li>Gerar mais<strong> tr\u00e1fego para o seu site<\/strong>, a partir dos an\u00fancios personalizados;<\/li>\n\n\n\n<li>Aumentar a <strong>convers\u00e3o de visitantes em leads<\/strong>, j\u00e1 que ser\u00e3o usu\u00e1rios que sabem mais o que est\u00e3o buscando;<\/li>\n\n\n\n<li><strong>Impulsionar as vendas do seu neg\u00f3cio<\/strong>, por meio dos produtos e servi\u00e7os expostos;<\/li>\n\n\n\n<li>Acesso ao<strong> <\/strong><a href=\"https:\/\/business.pinterest.com\/pt-br\/pinterest-business-partners\/\" target=\"_blank\" rel=\"noopener\"><strong>Pinterest Partner<\/strong><\/a>, que disponibiliza uma lista de parceiros que v\u00e3o ajudar no crescimento.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/leadster.com.br\/leads-qualificados-com-anuncios\/?utm_source=blog&amp;utm_medium=post&amp;utm_campaign=pinterest_ads\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-1024x341.webp\" alt=\"\" class=\"wp-image-6928\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-1024x341.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-300x100.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-768x256.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-1536x512.webp 1536w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-2048x683.webp 2048w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/09\/11-150x50.webp 150w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Quais Formatos de An\u00fancio Podem ser Criados no Pinterest Ads?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Quais-Formatos-de-Anuncio-Podem-ser-Criados-no-Pinterest-Ads.webp\" alt=\"Quais Formatos de An\u00fancio Podem ser Criados no Pinterest Ads?\" class=\"wp-image-9653\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Quais-Formatos-de-Anuncio-Podem-ser-Criados-no-Pinterest-Ads.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Quais-Formatos-de-Anuncio-Podem-ser-Criados-no-Pinterest-Ads-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Quais-Formatos-de-Anuncio-Podem-ser-Criados-no-Pinterest-Ads-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Assim como o <a href=\"https:\/\/leadster.com.br\/blog\/tiktok-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">TikTok Ads<\/a>, <a href=\"https:\/\/leadster.com.br\/blog\/linkedin-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn Ads<\/a> e <a href=\"https:\/\/leadster.com.br\/blog\/twitter-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter Ads<\/a>, o Pinterest tamb\u00e9m possui diversos formatos de an\u00fancio para voc\u00ea usar e abusar da sua criatividade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos agora conhecer os cinco tipos de an\u00fancio do Pinterest Ads!<\/p>\n\n\n\n<pre class=\"wp-block-verse\"><em>Leia tamb\u00e9m: <\/em><a href=\"https:\/\/leadster.com.br\/blog\/gestor-de-trafego\/\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Gestor de Tr\u00e1fego: Conhe\u00e7a os Pontos para Ter Sucesso na Profiss\u00e3o<\/em><\/a><\/pre>\n\n\n\n<h3 class=\"wp-block-heading\">Est\u00e1tico<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aqui estamos falando sobre o <strong>pin padr\u00e3o<\/strong> ou standard pin, em ingl\u00eas. Esse formato <strong>exp\u00f5e os produtos ou composi\u00e7\u00f5es em imagens verticais ou quadradas<\/strong>, com a propor\u00e7\u00e3o recomendada de 2:3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que, assim como em outras plataformas, logo abaixo da imagem vem o aviso de que aquele post \u00e9 um an\u00fancio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira o exemplo abaixo:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"598\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Estatico.webp\" alt=\"\" class=\"wp-image-9645\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Estatico.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Estatico-300x239.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Estatico-150x120.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">V\u00eddeo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aproveite esse formato para construir um<strong> storytelling inspirador<\/strong> que utilize seu produto ou servi\u00e7o, e utilize bem o tempo curto dispon\u00edvel &#8211; o recomendado \u00e9 ficar entre<strong> 6 e 15 segundos (podendo chegar at\u00e9 15 minutos)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outras especifica\u00e7\u00f5es de formato s\u00e3o: .mp4, .mov ou .m4v, com tamanho de at\u00e9 2 GB.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira <a href=\"https:\/\/pin.it\/3pav7JQ\" target=\"_blank\" data-type=\"URL\" data-id=\"https:\/\/pin.it\/3pav7JQ\" rel=\"noreferrer noopener\">o exemplo do Mercado Livre<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/pin.it\/3pav7JQ\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"750\" height=\"603\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Video.webp\" alt=\"\" class=\"wp-image-9656\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Video.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Video-300x241.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Video-150x121.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Shopping<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Tamb\u00e9m chamado de an\u00fancio de compras, o formato Shopping tem as mesmas especifica\u00e7\u00f5es dos pins est\u00e1ticos e em v\u00eddeo, por isso, pode causar algum tipo de confus\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por\u00e9m, o ponto-chave aqui \u00e9 que o esse <strong>formato \u00e9 usado diretamente para vender um produto do cat\u00e1logo<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Logo ao clicar no an\u00fancio, uma aba do produto ou servi\u00e7o j\u00e1 \u00e9 aberta e voc\u00ea j\u00e1 pode colocar no carrinho. Ou seja, o foco \u00e9 a convers\u00e3o para a sua loja virtual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos ao exemplo pr\u00e1tico:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"603\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/shopping.webp\" alt=\"\" class=\"wp-image-9655\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/shopping.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/shopping-300x241.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/shopping-150x121.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Carrossel<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O an\u00fancio em carrossel \u00e9 aquele que apresenta v\u00e1rias imagens para que o usu\u00e1rio deslize e se aprofunde no conte\u00fado da marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As especifica\u00e7\u00f5es de formato s\u00e3o as mesmas do formato padr\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pr\u00f3prio Pinterest Ads mostra para voc\u00ea como \u00e9 o resultado final desse formato, confira:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Carousel Preview: REI\" width=\"750\" height=\"563\" src=\"https:\/\/www.youtube.com\/embed\/6O6vicFzbE4?start=22&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Cole\u00e7\u00f5es<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Por fim, temos o an\u00fancio tipo cole\u00e7\u00f5es. Esse formato permite utilizar uma<strong> imagem principal destacada<\/strong> e, logo abaixo, <strong>tr\u00eas imagens menores<\/strong>, as quais se relacionam com a principal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja o exemplo do pr\u00f3prio Pinterest:<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"603\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/colecao.webp\" alt=\"\" class=\"wp-image-9643\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/colecao.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/colecao-300x241.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/colecao-150x121.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o Valor do An\u00fancio no Pinterest Ads?<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Qual-o-valor-do-anuncio-no-Pinterest.webp\" alt=\"Qual o Valor do An\u00fancio no Pinterest Ads?\" class=\"wp-image-9654\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Qual-o-valor-do-anuncio-no-Pinterest.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Qual-o-valor-do-anuncio-no-Pinterest-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Qual-o-valor-do-anuncio-no-Pinterest-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo levantamento do <a href=\"https:\/\/www.statista.com\/statistics\/872682\/social-media-advertising-cpc\/\" target=\"_blank\" rel=\"noreferrer noopener\">Statista See More<\/a>, o <strong>custo m\u00e9dio <\/strong>dos an\u00fancios do Pinterest em 2021 foi de<strong> US$ 1,50 por clique<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se compararmos com o Facebook Ads, veremos o custo m\u00e9dio entre R$ 2,00 e R$ 12,00, conforme levantamento do <a href=\"https:\/\/www.wordstream.com\/blog\/ws\/2017\/02\/28\/facebook-advertising-benchmarks\" target=\"_blank\" rel=\"noreferrer noopener\">WordStream<\/a> e <a href=\"https:\/\/adespresso.com\/faq\/can-you-provide-benchmarks-for-facebook-advertising-costs\/\" target=\"_blank\" rel=\"noreferrer noopener\">AdEspresso<\/a>. J\u00e1 no <a href=\"https:\/\/leadster.com.br\/blog\/como-anunciar-no-google-ads\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Ads<\/a> \u00e9 necess\u00e1rio investir, no m\u00ednimo, R$ 5,00 por dia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com destaque para o formato <strong>Shopping que gerou retorno 5 vezes maior em seus gastos com an\u00fancios<\/strong>, al\u00e9m de serem<a href=\"https:\/\/business.pinterest.com\/en\/success-stories\/it-cosmetics\/?7kVWhTYfqbd8axuGXr9MBP=parent_filter%3D5YbTy9HMOSLV3qGtLhYpfg%26child_filters%3D7lu9K97BUsdnaqi4tKXMdz\" target=\"_blank\" rel=\"noreferrer noopener\"> 89% mais econ\u00f4micos<\/a> do que outras plataformas utilizadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que voc\u00ea pode definir um or\u00e7amento di\u00e1rio m\u00e1ximo para suas campanhas publicit\u00e1rias no Pinterest.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Passo a passo para criar e editar uma campanha no Pinterest Ads<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Passo-a-passo-para-criar-e-editar-uma-campanha-no-Pinterest-Ads.webp\" alt=\"Passo a passo para criar e editar uma campanha no Pinterest Ads\" class=\"wp-image-9650\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Passo-a-passo-para-criar-e-editar-uma-campanha-no-Pinterest-Ads.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Passo-a-passo-para-criar-e-editar-uma-campanha-no-Pinterest-Ads-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/Passo-a-passo-para-criar-e-editar-uma-campanha-no-Pinterest-Ads-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Em apenas 6 passos voc\u00ea ter\u00e1 sua campanha no Pinterest Ads no ar e j\u00e1 poder\u00e1 monitorar os resultados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Confira:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Passo 1: Crie uma conta comercial e instale a tag do Pinterest<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Para come\u00e7ar, \u00e9 necess\u00e1rio <strong>criar uma conta comercial no aplicativo<\/strong>. Basta acessar a p\u00e1gina do <a href=\"https:\/\/ads.pinterest.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pinterest Ads<\/a> e clicar em \u201cEntrar\u201d ou \u201cCriar Conta\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-1.webp\" alt=\"\" class=\"wp-image-9647\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-1.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-1-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-1-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A partir do cadastro, a plataforma vai te fazer uma <strong>s\u00e9rie de perguntas espec\u00edficas para entender sobre o seu nicho de mercado <\/strong>e quais s\u00e3o seus objetivos com a conta <em>business <\/em>no Pinterest.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algumas perguntas s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Qual nome voc\u00ea quer dar para o perfil?<\/li>\n\n\n\n<li>Voc\u00ea possui um site?<\/li>\n\n\n\n<li>Qual o foco da sua marca?<\/li>\n\n\n\n<li>Quais s\u00e3o os seus objetivos?<\/li>\n\n\n\n<li>Como voc\u00ea descreve a sua empresa?<\/li>\n\n\n\n<li>Tem interesse em veicular an\u00fancios no Pinterest?<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-2.webp\" alt=\"\" class=\"wp-image-9648\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-2.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-2-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-2-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s esse preenchimento, seu cadastro ser\u00e1 conclu\u00eddo e voc\u00ea vai receber o contato de um especialista em an\u00fancios do pr\u00f3prio Pinterest.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Passo 2: Escolha a meta da sua campanha<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Com o cadastro feito, chegou o momento de <a href=\"https:\/\/leadster.com.br\/blog\/definir-objetivo-de-campanha\/\" target=\"_blank\" rel=\"noreferrer noopener\">definir seu objetivo de campanha<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As metas j\u00e1 estabelecidas no Pinterest Ads s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Reconhecimento de marca;<\/li>\n\n\n\n<li>Visualiza\u00e7\u00e3o de v\u00eddeo;<\/li>\n\n\n\n<li>Tr\u00e1fego para o site;<\/li>\n\n\n\n<li>Convers\u00e3o;<\/li>\n\n\n\n<li>Cat\u00e1logo de compras.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Passo 3: Defina o or\u00e7amento da campanha<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Ap\u00f3s estabelecer o que ser\u00e1 alcan\u00e7ado por sua campanha, vamos definir o or\u00e7amento, ou seja, quanto voc\u00ea vai investir com os an\u00fancios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nessa etapa, defina se o <strong>or\u00e7amento ser\u00e1 di\u00e1rio ou total<\/strong>, o<strong> limite de gastos<\/strong> e a<strong> programa\u00e7\u00e3o<\/strong>, ou seja, quando os an\u00fancios v\u00e3o ao ar.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"750\" height=\"400\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-3.webp\" alt=\"\" class=\"wp-image-9649\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-3.webp 750w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-3-300x160.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/12\/passo-3-150x80.webp 150w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Passo 4: Defina o seu p\u00fablico-alvo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vamos definir agora para quem voc\u00ea est\u00e1 produzindo esses an\u00fancios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No Pinterest Ads, voc\u00ea pode segmentar seu p\u00fablico-alvo pelo <strong>g\u00eanero, localiza\u00e7\u00e3o, idioma e dispositivo<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que voc\u00ea pode importar listas de clientes ou leads j\u00e1 existentes em sua base de dados.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/leadster.com.br\/materiais\/framework-de-publicos\/?utm_source=banner_blog&amp;utm_medium=organic&amp;utm_campaign=post_tofu&amp;utm_content=pinterest_ads\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"382\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas-1024x382.webp\" alt=\"\" class=\"wp-image-10495\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas-1024x382.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas-300x112.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas-768x287.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas-150x56.webp 150w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2023\/01\/banner_Framework-de-Publicos-e-Peronas.webp 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h3 class=\"wp-block-heading\">Passo 5: Escolha os pins que ser\u00e3o anunciados<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Estamos chegando nos \u201cfinalmentes\u201d da cria\u00e7\u00e3o de seu an\u00fancio no Pinterest Ads.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pen\u00faltimo passo \u00e9 a<strong> escolha dos pins que v\u00e3o entrar na campanha.<\/strong> Al\u00e9m de escolh\u00ea-los, lembre-se que eles devem estar qualificados, para isso, siga os seguintes pontos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Deixe-os salvos em seu perfil;<\/li>\n\n\n\n<li>N\u00e3o os salve em pastas secretas;<\/li>\n\n\n\n<li>Defina as URLs de destino;<\/li>\n\n\n\n<li>N\u00e3o apresente v\u00eddeos de terceiros ou GIFs.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Passo 6: Monitore o desempenho da campanha<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">O \u00faltimo passo \u00e9 otimizar ainda mais sua campanha. Para isso, \u00e9 necess\u00e1rio ampliar o p\u00fablico, aumentar o or\u00e7amento, experimentar formatos diferentes ou planejar eventos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mas, para saber o que deve ser otimizado, voc\u00ea precisa<strong> acompanhar o desempenho de suas campanhas anteriores<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O pr\u00f3prio Pinterest Ads j\u00e1 pensou nessa etapa, ent\u00e3o voc\u00ea precisa apenas <strong>monitorar KPIs importantes<\/strong>. Para defini-los acesse a \u201cHome do Pinterest Business\u201d \u2192 \u201cMenu superior \u2192 \u201cAn\u00fancios\u201d \u2192&nbsp; \u201cRelat\u00f3rios\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algumas das <a href=\"https:\/\/leadster.com.br\/blog\/metricas-de-midia-paga\/\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e9tricas de m\u00eddia paga<\/a> s\u00e3o:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gasto total do per\u00edodo;<\/li>\n\n\n\n<li>Impress\u00f5es;<\/li>\n\n\n\n<li>Cliques no pin;<\/li>\n\n\n\n<li>Cliques de sa\u00edda, que levaram para uma a\u00e7\u00e3o fora do aplicativo;<\/li>\n\n\n\n<li>Custo m\u00e9dio por resultado;<\/li>\n\n\n\n<li>CTR.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">E a\u00ed, j\u00e1 est\u00e1 expert no Pinterest Ads?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se voc\u00ea n\u00e3o quer parar por aqui, saiba que a Leadster tamb\u00e9m \u00e9 sucesso quando o assunto \u00e9 an\u00fancio pago. Por isso, se liga nesse conte\u00fado completo sobre o assunto: <a href=\"https:\/\/leadster.com.br\/midia-paga\/\">M\u00eddia Pa<\/a><a href=\"https:\/\/leadster.com.br\/midia-paga\/\" target=\"_blank\" rel=\"noreferrer noopener\">ga &#8211; O Guia Completo<\/a>!<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/leadster.com.br\/midia-paga\/\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" width=\"1024\" height=\"341\" src=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-1024x341.webp\" alt=\"\" class=\"wp-image-7691\" srcset=\"https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-1024x341.webp 1024w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-300x100.webp 300w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-768x256.webp 768w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga-150x50.webp 150w, https:\/\/leadster.com.br\/blog\/wp-content\/uploads\/2022\/10\/Banner_pillar_page_midia-paga.webp 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ainda existem algumas pessoas que subestimam o poder do Pinterest, como se a plataforma fosse apenas um local para armazenar fotos e ideias.&nbsp; Mas, voc\u00ea sabia que usu\u00e1rios da rede est\u00e3o dispostos a comprar 50% mais do que aqueles que n\u00e3o est\u00e3o no canal? Pois \u00e9, essa plataforma pode te [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9651,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[68],"tags":[],"class_list":["post-9601","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-midia-paga"],"_links":{"self":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/9601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/comments?post=9601"}],"version-history":[{"count":1,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/9601\/revisions"}],"predecessor-version":[{"id":12038,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/posts\/9601\/revisions\/12038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/media\/9651"}],"wp:attachment":[{"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/media?parent=9601"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/categories?post=9601"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/leadster.com.br\/blog\/wp-json\/wp\/v2\/tags?post=9601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}